{"id":4015,"date":"2025-11-05T10:33:13","date_gmt":"2025-11-05T09:33:13","guid":{"rendered":"https:\/\/www.dinopaoli.com\/prodotto\/dplift-830-r\/"},"modified":"2025-11-05T10:39:26","modified_gmt":"2025-11-05T09:39:26","slug":"dplift-830-r","status":"publish","type":"prodotto","link":"https:\/\/www.dinopaoli.com\/en\/product\/dplift-830-r\/","title":{"rendered":"DPLIFT 830 R"},"content":{"rendered":"<p>Practical and effective oleopneumatic lifts for heavy vehicles.<br \/>\nIdeal for workshops, tire shops and body shops.<\/p>\n","protected":false},"featured_media":1896,"parent":0,"template":"","meta":{"_acf_changed":false},"applicazione-prodotto":[115],"settore-prodotto":[77,79],"attacco-quadro-prodotto":[],"tecnologia-prodotto":[94,90],"tipologia-prodotto":[86],"class_list":["post-4015","prodotto","type-prodotto","status-publish","has-post-thumbnail","hentry","applicazione-prodotto-heavy-vehicles-trucks-buses-and-industrial-and-vehicles","settore-prodotto-automotive-en","settore-prodotto-industry-en","tecnologia-prodotto-hydraulic","tecnologia-prodotto-pneumatic","tipologia-prodotto-lifts"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DPLIFT 830 R | Dino Paoli Srl<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dinopaoli.com\/en\/product\/dplift-830-r\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DPLIFT 830 R | Dino Paoli Srl\" \/>\n<meta property=\"og:description\" content=\"Practical and effective oleopneumatic lifts for heavy vehicles. Ideal for workshops, tire shops and body shops.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dinopaoli.com\/en\/product\/dplift-830-r\/\" \/>\n<meta property=\"og:site_name\" content=\"Dino Paoli Srl\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-05T09:39:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dinopaoli.com\/wp-content\/uploads\/DPLIFT830R_NEUTRAL.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.dinopaoli.com\/en\/product\/dplift-830-r\/\",\"url\":\"https:\/\/www.dinopaoli.com\/en\/product\/dplift-830-r\/\",\"name\":\"DPLIFT 830 R | Dino Paoli Srl\",\"isPartOf\":{\"@id\":\"https:\/\/www.dinopaoli.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.dinopaoli.com\/en\/product\/dplift-830-r\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.dinopaoli.com\/en\/product\/dplift-830-r\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.dinopaoli.com\/wp-content\/uploads\/DPLIFT830R_NEUTRAL.webp\",\"datePublished\":\"2025-11-05T09:33:13+00:00\",\"dateModified\":\"2025-11-05T09:39:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.dinopaoli.com\/en\/product\/dplift-830-r\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.dinopaoli.com\/en\/product\/dplift-830-r\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.dinopaoli.com\/en\/product\/dplift-830-r\/#primaryimage\",\"url\":\"https:\/\/www.dinopaoli.com\/wp-content\/uploads\/DPLIFT830R_NEUTRAL.webp\",\"contentUrl\":\"https:\/\/www.dinopaoli.com\/wp-content\/uploads\/DPLIFT830R_NEUTRAL.webp\",\"width\":720,\"height\":720,\"caption\":\"DPLIFT 830 R\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.dinopaoli.com\/en\/product\/dplift-830-r\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.dinopaoli.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\/\/www.dinopaoli.com\/en\/prodotti\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DPLIFT 830 R\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.dinopaoli.com\/en\/#website\",\"url\":\"https:\/\/www.dinopaoli.com\/en\/\",\"name\":\"Dino Paoli\",\"description\":\"Da oltre 50 anni, avvitatori e tools per ogni sfida.\",\"publisher\":{\"@id\":\"https:\/\/www.dinopaoli.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.dinopaoli.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.dinopaoli.com\/en\/#organization\",\"name\":\"Dino Paoli\",\"url\":\"https:\/\/www.dinopaoli.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.dinopaoli.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.dinopaoli.com\/wp-content\/uploads\/logo-dino-paoli-w.svg\",\"contentUrl\":\"https:\/\/www.dinopaoli.com\/wp-content\/uploads\/logo-dino-paoli-w.svg\",\"caption\":\"Dino Paoli\"},\"image\":{\"@id\":\"https:\/\/www.dinopaoli.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/it.linkedin.com\/company\/dino-paoli\",\"https:\/\/www.youtube.com\/@dinopaolisrl\",\"https:\/\/www.instagram.com\/dinopaoli\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DPLIFT 830 R | Dino Paoli Srl","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dinopaoli.com\/en\/product\/dplift-830-r\/","og_locale":"en_US","og_type":"article","og_title":"DPLIFT 830 R | Dino Paoli Srl","og_description":"Practical and effective oleopneumatic lifts for heavy vehicles. Ideal for workshops, tire shops and body shops.","og_url":"https:\/\/www.dinopaoli.com\/en\/product\/dplift-830-r\/","og_site_name":"Dino Paoli Srl","article_modified_time":"2025-11-05T09:39:26+00:00","og_image":[{"width":720,"height":720,"url":"https:\/\/www.dinopaoli.com\/wp-content\/uploads\/DPLIFT830R_NEUTRAL.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.dinopaoli.com\/en\/product\/dplift-830-r\/","url":"https:\/\/www.dinopaoli.com\/en\/product\/dplift-830-r\/","name":"DPLIFT 830 R | Dino Paoli Srl","isPartOf":{"@id":"https:\/\/www.dinopaoli.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.dinopaoli.com\/en\/product\/dplift-830-r\/#primaryimage"},"image":{"@id":"https:\/\/www.dinopaoli.com\/en\/product\/dplift-830-r\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dinopaoli.com\/wp-content\/uploads\/DPLIFT830R_NEUTRAL.webp","datePublished":"2025-11-05T09:33:13+00:00","dateModified":"2025-11-05T09:39:26+00:00","breadcrumb":{"@id":"https:\/\/www.dinopaoli.com\/en\/product\/dplift-830-r\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dinopaoli.com\/en\/product\/dplift-830-r\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dinopaoli.com\/en\/product\/dplift-830-r\/#primaryimage","url":"https:\/\/www.dinopaoli.com\/wp-content\/uploads\/DPLIFT830R_NEUTRAL.webp","contentUrl":"https:\/\/www.dinopaoli.com\/wp-content\/uploads\/DPLIFT830R_NEUTRAL.webp","width":720,"height":720,"caption":"DPLIFT 830 R"},{"@type":"BreadcrumbList","@id":"https:\/\/www.dinopaoli.com\/en\/product\/dplift-830-r\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.dinopaoli.com\/en\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.dinopaoli.com\/en\/prodotti\/"},{"@type":"ListItem","position":3,"name":"DPLIFT 830 R"}]},{"@type":"WebSite","@id":"https:\/\/www.dinopaoli.com\/en\/#website","url":"https:\/\/www.dinopaoli.com\/en\/","name":"Dino Paoli","description":"Da oltre 50 anni, avvitatori e tools per ogni sfida.","publisher":{"@id":"https:\/\/www.dinopaoli.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dinopaoli.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.dinopaoli.com\/en\/#organization","name":"Dino Paoli","url":"https:\/\/www.dinopaoli.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dinopaoli.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.dinopaoli.com\/wp-content\/uploads\/logo-dino-paoli-w.svg","contentUrl":"https:\/\/www.dinopaoli.com\/wp-content\/uploads\/logo-dino-paoli-w.svg","caption":"Dino Paoli"},"image":{"@id":"https:\/\/www.dinopaoli.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/it.linkedin.com\/company\/dino-paoli","https:\/\/www.youtube.com\/@dinopaolisrl","https:\/\/www.instagram.com\/dinopaoli"]}]}},"_links":{"self":[{"href":"https:\/\/www.dinopaoli.com\/en\/wp-json\/wp\/v2\/prodotto\/4015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dinopaoli.com\/en\/wp-json\/wp\/v2\/prodotto"}],"about":[{"href":"https:\/\/www.dinopaoli.com\/en\/wp-json\/wp\/v2\/types\/prodotto"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dinopaoli.com\/en\/wp-json\/wp\/v2\/media\/1896"}],"wp:attachment":[{"href":"https:\/\/www.dinopaoli.com\/en\/wp-json\/wp\/v2\/media?parent=4015"}],"wp:term":[{"taxonomy":"applicazione-prodotto","embeddable":true,"href":"https:\/\/www.dinopaoli.com\/en\/wp-json\/wp\/v2\/applicazione-prodotto?post=4015"},{"taxonomy":"settore-prodotto","embeddable":true,"href":"https:\/\/www.dinopaoli.com\/en\/wp-json\/wp\/v2\/settore-prodotto?post=4015"},{"taxonomy":"attacco-quadro-prodotto","embeddable":true,"href":"https:\/\/www.dinopaoli.com\/en\/wp-json\/wp\/v2\/attacco-quadro-prodotto?post=4015"},{"taxonomy":"tecnologia-prodotto","embeddable":true,"href":"https:\/\/www.dinopaoli.com\/en\/wp-json\/wp\/v2\/tecnologia-prodotto?post=4015"},{"taxonomy":"tipologia-prodotto","embeddable":true,"href":"https:\/\/www.dinopaoli.com\/en\/wp-json\/wp\/v2\/tipologia-prodotto?post=4015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}